{"id":3317,"date":"2025-09-27T00:00:00","date_gmt":"2025-09-26T22:00:00","guid":{"rendered":"http:\/\/apdev.ovh\/saludon\/?p=3317"},"modified":"2025-11-11T16:24:13","modified_gmt":"2025-11-11T15:24:13","slug":"que-es-y-como-se-realiza-una-gastroscopia","status":"publish","type":"post","link":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/","title":{"rendered":"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia"},"content":{"rendered":"<p>Las molestias abdominales son comunes en muchas personas. Pueden deberse a diferentes causas y es importante que el m\u00e9dico las conozca para poder poner un tratamiento. Por eso hay pruebas espec\u00edficas para saber si existe alguna patolog\u00eda concreta, como la <strong>gastroscopia o endoscopia digestiva alta<\/strong>. Este examen se realiza para evaluar las causas del dolor, en personas que presentan n\u00e1useas, dificultad para tragar, acidez o ardor, entre otros s\u00edntomas.<!--more-->Existen muchos motivos para solicitar una gastroscopia, pero los m\u00e1s frecuentes son:<\/p>\n<ul>\n<li>Problemas en el <em>es\u00f3fago, est\u00f3mago<\/em> (gastritis, \u00falceras o tumores) o <em>duodeno.<\/em><\/li>\n<li><em>Hernia de hiato.<\/em><\/li>\n<li><em>Reflujo<\/em>.<\/li>\n<li>Personas con <em>anemias ferrop\u00e9nicas<\/em>, <em>heces negras<\/em>, <em>p\u00e9rdida de peso sin motivo<\/em>, <em>cirrosis hep\u00e1tica.<\/em><\/li>\n<li>Para diagnosticar enfermedades como la <em>celiaqu\u00eda<\/em>.<\/li>\n<\/ul>\n<p>Es un m\u00e9todo muy eficaz para valorar hemorragias que provienen de la zona digestiva alta, ya que extrayendo peque\u00f1as muestras de mucosa se puede saber si la persona tiene lesiones benignas o malignas.<\/p>\n<h2>Preparaci\u00f3n y desarrollo de la prueba<\/h2>\n<p>Esta prueba consiste en una<strong> exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno<\/strong>, que se lleva a cabo mediante un endoscopio o tubo flexible de un cent\u00edmetro de di\u00e1metro y algo m\u00e1s de 100 cm de largo. Este aparato se introduce por la boca del paciente y avanza hasta el intestino superior. Cuenta con una c\u00e1mara que permite ver el interior del intestino a trav\u00e9s de un monitor de v\u00eddeo que muestra las im\u00e1genes para ser analizadas. Con esta t\u00e9cnica, que realiza el m\u00e9dico especialista en Aparato Digestivo, se pueden detectar tumores en estadio precoz.<\/p>\n<p>El tubo tiene varios canales, que permiten tambi\u00e9n introducir instrumentos necesarios, por ejemplo, para la toma de biopsias o para extirpar cuerpos extra\u00f1os o p\u00f3lipos. Lo bueno es que el aparato, aunque es molesto, no interfiere en la respiraci\u00f3n del paciente y no suele causar dolor. No obstante, para las personas que no lo toleran existe la opci\u00f3n de realizar esta prueba con sedaci\u00f3n o anestesia.<\/p>\n<p>Antes de hacerse una gastroscopia, la persona <strong>necesita una preparaci\u00f3n espec\u00edfica<\/strong> para que la prueba salga lo mejor posible. En primer lugar debe de estar en ayunas, por lo menos desde la noche anterior, para que el est\u00f3mago est\u00e9 vac\u00edo. Quienes toman medicaci\u00f3n deben comunic\u00e1rselo al m\u00e9dico para que les indique c\u00f3mo deben de realizar la ingesta en este caso. Lo mismo ocurre con aquellos que toman anticoagulantes o tienen alguna enfermedad que el especialista debe conocer.<\/p>\n<p>El resultado se sabe de manera inmediata, una vez terminada la prueba. No ocurre as\u00ed cuando se han tomado muestras que hay que analizar en el laboratorio. En ese caso el paciente debe de esperar unos d\u00edas hasta tener una conclusi\u00f3n.<\/p>\n<p>Si presentas molestias estomacales no dudes en acudir a <span style=\"color: #009ee0;\"><a style=\"color: #009ee0;\" href=\"https:\/\/www.saludonnet.com\/centros-medicos\/aparato-digestivo\/1042-consulta\"><strong>consulta de Aparato Digestivo<\/strong><\/a><\/span> y comunicar al m\u00e9dico qu\u00e9 es lo que te ocurre. Si el especialista considera que debes <a href=\"https:\/\/www.saludonnet.com\/centros-medicos\/cirugia-general-y-del-aparato-digestivo\/6087-ff-gastroscopia-endoscopia-digestiva-alta\"><strong><span style=\"color: #009ee0;\">realizarte una gastroscopia<\/span><\/strong><\/a>, en\u00a0<a href=\"https:\/\/www.saludonnet.com\/\"><strong><span style=\"color: #009ee0;\"><strong><span style=\"color: #009ee0;\">SaludOnNet<\/span> <\/strong><\/span> <\/strong><\/a>ponemos a tu disposici\u00f3n a los mejores especialistas encargados de hacer esta prueba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio.<\/p>\n","protected":false},"author":20,"featured_media":1635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[221],"class_list":["post-3317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aparato-digestivo","tag-1042-consulta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia<\/title>\n<meta name=\"description\" content=\"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia\" \/>\n<meta property=\"og:description\" content=\"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio. Es una prueba que no es dolorosa y ayuda a detectar tumores en estadio precoz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog SaludOnNet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/SaludOnNet\/214957498526536\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T15:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2019\/05\/gastroscopia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo M\u00e9dico de SaludOnNet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia\" \/>\n<meta name=\"twitter:description\" content=\"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio. Es una prueba que no es dolorosa y ayuda a detectar tumores en estadio precoz.\" \/>\n<meta name=\"twitter:creator\" content=\"@saludonnet\" \/>\n<meta name=\"twitter:site\" content=\"@saludonnet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo M\u00e9dico de SaludOnNet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/\"},\"author\":{\"name\":\"Equipo M\u00e9dico de SaludOnNet\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/person\\\/50995e01cc9d6c9f29ae18d979eeff1b\"},\"headline\":\"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia\",\"datePublished\":\"2025-09-26T22:00:00+00:00\",\"dateModified\":\"2025-11-11T15:24:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/gastroscopia.jpg\",\"keywords\":[\"Consulta de Aparato Digestivo\"],\"articleSection\":[\"Aparato Digestivo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/\",\"name\":\"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/gastroscopia.jpg\",\"datePublished\":\"2025-09-26T22:00:00+00:00\",\"dateModified\":\"2025-11-11T15:24:13+00:00\",\"description\":\"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/gastroscopia.jpg\",\"contentUrl\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/gastroscopia.jpg\",\"width\":800,\"height\":400,\"caption\":\"gastroscopia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/que-es-y-como-se-realiza-una-gastroscopia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aparato Digestivo\",\"item\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/topic\\\/aparato-digestivo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/\",\"name\":\"Blog SaludOnNet\",\"description\":\"Un espacio donde encontrar\u00e1s consejos y art\u00edculos para cuidar de tu salud\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#organization\",\"name\":\"SaludOnNet\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Logo-SaludOnNet.png\",\"contentUrl\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Logo-SaludOnNet.png\",\"width\":1140,\"height\":377,\"caption\":\"SaludOnNet\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/SaludOnNet\\\/214957498526536\",\"https:\\\/\\\/x.com\\\/saludonnet\",\"https:\\\/\\\/www.instagram.com\\\/saludonnet\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/saludonnet\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCag68GsnagqzNb6C3G-S9vQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/person\\\/50995e01cc9d6c9f29ae18d979eeff1b\",\"name\":\"Equipo M\u00e9dico de SaludOnNet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g\",\"caption\":\"Equipo M\u00e9dico de SaludOnNet\"},\"description\":\"Art\u00edculo elaborado por el equipo m\u00e9dico de SaludOnNet, compuesto por especialistas destacados en su \u00e1rea.\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/author\\\/saludonnet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia","description":"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia","og_description":"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio. Es una prueba que no es dolorosa y ayuda a detectar tumores en estadio precoz.","og_url":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/","og_site_name":"Blog SaludOnNet","article_publisher":"https:\/\/www.facebook.com\/pages\/SaludOnNet\/214957498526536","article_published_time":"2025-09-26T22:00:00+00:00","article_modified_time":"2025-11-11T15:24:13+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2019\/05\/gastroscopia.jpg","type":"image\/jpeg"}],"author":"Equipo M\u00e9dico de SaludOnNet","twitter_card":"summary_large_image","twitter_title":"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia","twitter_description":"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio. Es una prueba que no es dolorosa y ayuda a detectar tumores en estadio precoz.","twitter_creator":"@saludonnet","twitter_site":"@saludonnet","twitter_misc":{"Escrito por":"Equipo M\u00e9dico de SaludOnNet","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#article","isPartOf":{"@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/"},"author":{"name":"Equipo M\u00e9dico de SaludOnNet","@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/person\/50995e01cc9d6c9f29ae18d979eeff1b"},"headline":"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia","datePublished":"2025-09-26T22:00:00+00:00","dateModified":"2025-11-11T15:24:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/www.saludonnet.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#primaryimage"},"thumbnailUrl":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2019\/05\/gastroscopia.jpg","keywords":["Consulta de Aparato Digestivo"],"articleSection":["Aparato Digestivo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/","url":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/","name":"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia","isPartOf":{"@id":"https:\/\/www.saludonnet.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#primaryimage"},"image":{"@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#primaryimage"},"thumbnailUrl":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2019\/05\/gastroscopia.jpg","datePublished":"2025-09-26T22:00:00+00:00","dateModified":"2025-11-11T15:24:13+00:00","description":"La gastroscopia o endoscopia digestiva alta consiste en una exploraci\u00f3n del es\u00f3fago, el est\u00f3mago y el duodeno, que se lleva a cabo mediante un endoscopio.","breadcrumb":{"@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#primaryimage","url":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2019\/05\/gastroscopia.jpg","contentUrl":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2019\/05\/gastroscopia.jpg","width":800,"height":400,"caption":"gastroscopia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.saludonnet.com\/blog\/que-es-y-como-se-realiza-una-gastroscopia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.saludonnet.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Aparato Digestivo","item":"https:\/\/www.saludonnet.com\/blog\/topic\/aparato-digestivo\/"},{"@type":"ListItem","position":3,"name":"Qu\u00e9 es y c\u00f3mo se realiza una Gastroscopia"}]},{"@type":"WebSite","@id":"https:\/\/www.saludonnet.com\/blog\/#website","url":"https:\/\/www.saludonnet.com\/blog\/","name":"Blog SaludOnNet","description":"Un espacio donde encontrar\u00e1s consejos y art\u00edculos para cuidar de tu salud","publisher":{"@id":"https:\/\/www.saludonnet.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saludonnet.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.saludonnet.com\/blog\/#organization","name":"SaludOnNet","url":"https:\/\/www.saludonnet.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2019\/07\/Logo-SaludOnNet.png","contentUrl":"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2019\/07\/Logo-SaludOnNet.png","width":1140,"height":377,"caption":"SaludOnNet"},"image":{"@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/SaludOnNet\/214957498526536","https:\/\/x.com\/saludonnet","https:\/\/www.instagram.com\/saludonnet\/","https:\/\/www.linkedin.com\/company\/saludonnet\/","https:\/\/www.youtube.com\/channel\/UCag68GsnagqzNb6C3G-S9vQ"]},{"@type":"Person","@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/person\/50995e01cc9d6c9f29ae18d979eeff1b","name":"Equipo M\u00e9dico de SaludOnNet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g","caption":"Equipo M\u00e9dico de SaludOnNet"},"description":"Art\u00edculo elaborado por el equipo m\u00e9dico de SaludOnNet, compuesto por especialistas destacados en su \u00e1rea.","url":"https:\/\/www.saludonnet.com\/blog\/author\/saludonnet\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts\/3317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/comments?post=3317"}],"version-history":[{"count":7,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts\/3317\/revisions"}],"predecessor-version":[{"id":14829,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts\/3317\/revisions\/14829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/media\/1635"}],"wp:attachment":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/media?parent=3317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/categories?post=3317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/tags?post=3317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}