{"id":11287,"date":"2026-01-10T16:17:00","date_gmt":"2026-01-10T15:17:00","guid":{"rendered":"https:\/\/www.saludonnet.com\/blog\/?p=11287"},"modified":"2026-01-29T17:00:39","modified_gmt":"2026-01-29T16:00:39","slug":"dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador","status":"publish","type":"post","link":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/","title":{"rendered":"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador"},"content":{"rendered":"\n<p>La cabeza del h\u00famero est\u00e1 rodeada por una\nestructura de tendones y m\u00fasculos, que se denominan <strong>manguito rotador<\/strong>.\nSon el subescapular, el supraespinoso, el infraespinoso y el redondo menor,\nencargados de favorecer los movimientos del hombro y la esc\u00e1pula. La lesi\u00f3n del\nmanguito rotador se produce cuando el hueso acromion, situado en la parte alta\ny externa del om\u00f3plato, fricciona con los tendones. <\/p>\n\n\n\n<p>Las estructuras pueden lesionarse de diferentes\nformas y por distintas causas: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Aguda<\/strong>.\n<ul class=\"wp-block-list\">\n<li>Como consecuencia de un <strong>traumatismo o\nca\u00edda sobre el hombro<\/strong> o por coger un <strong>peso excesivo<\/strong>. Cuando esto ocurre\nel hombro puede chocar con el acromion y romper el manguito rotador o desgarrar\nel tend\u00f3n de su inserci\u00f3n.<\/li>\n\n\n\n<li><strong>Luxaciones<\/strong>. Cuando se\nproducen en personas mayores es importante descartar que no se ha habido una\nrotura de los tendones, que est\u00e1n m\u00e1s debilitados. <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.elsevier.es\/es-revista-revista-espanola-cirugia-ortopedica-traumatologia-129-articulo-reparacion-lesiones-cronicas-del-manguito-S1888441516300625\">Cr\u00f3nica<\/a><\/strong>.\nEs muy frecuente, a causa de enfermedades reum\u00e1ticas, diabetes\u2026etc. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Caracter\u00edsticas y s\u00edntomas manguito rotador<\/strong> <\/h2>\n\n\n\n<p><strong><a href=\"https:\/\/accedacris.ulpgc.es\/bitstream\/10553\/5992\/1\/0514198_00013_0009.pdf\">La\nlesi\u00f3n del manguito rotador<\/a><\/strong> produce un <strong>dolor en el hombro, que se\nirradia a la parte lateral<\/strong>. Es frecuente que aparezca <strong>por la noche y al\nrealizar movimientos<\/strong>. Si hay <strong>crepitaci\u00f3n o chasquido<\/strong> al moverlo puede\nser a causa de una rotura de los tendones o, en personas de m\u00e1s edad, a la <strong><a href=\"https:\/\/www.saludonnet.com\/blog\/topic\/traumatologia-y-cirugia-ortopedica\/\">artrosis<\/a><\/strong>.\n<\/p>\n\n\n\n<p>No obstante, este ruido hay veces que solo est\u00e1\ncausado por una <strong><a href=\"https:\/\/www.saludonnet.com\/blog\/que-es-una-tendinopatia-y-como-se-trata\/\">tendinitis<\/a><\/strong>,\npor lo que es importante que el m\u00e9dico vea al paciente para realizar un buen\ndiagn\u00f3stico a trav\u00e9s de la exploraci\u00f3n f\u00edsica y las pruebas complementarias. <\/p>\n\n\n\n<p>Los principales s\u00edntomas que produce la rotura o\nla inflamaci\u00f3n del manguito rotador son: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Dolor en el hombro al levantar el brazo<\/em>.\n&nbsp;Sucede generalmente cuando se practica\nun deporte o una actividad f\u00edsica intensa. &nbsp;<\/li>\n\n\n\n<li><em>Molestias nocturnas<\/em>.\n<\/li>\n\n\n\n<li><em>Crepitaci\u00f3n<\/em>. Se dan con\nm\u00e1s frecuencia cuando se producen roturas completas de la estructura. En estos\ncasos la cabeza humeral queda descubierta y fricciona con el acromion, produciendo\nese sonido o chasquido. &nbsp;<\/li>\n\n\n\n<li><em>P\u00e9rdida de fuerza aguda o progresiva<\/em>.\nSucede cuando los tendones se rompen o se retraen y tambi\u00e9n cuando se inflaman,\nporque al existir dolor se utilizan menos. &nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Manguito rotador tratamiento y diagn\u00f3stico<\/strong> <\/h2>\n\n\n\n<p>El m\u00e9dico debe realiza una exploraci\u00f3n f\u00edsica para\npoder diagnosticar la patolog\u00eda, analizando la movilidad, el dolor y comparando\nun hombro con el otro. Existen unas pruebas espec\u00edficas para conocer en qu\u00e9\ntend\u00f3n se ha producido la lesi\u00f3n. Las pruebas de imagen tambi\u00e9n son muy \u00fatiles,\nsobre todo la <strong><a href=\"https:\/\/www.saludonnet.com\/blog\/?s=ecograf%C3%ADa\">ecograf\u00eda<\/a><\/strong>\ny la <strong>resonancia magn\u00e9tica<\/strong>. &nbsp;<\/p>\n\n\n\n<p>El tratamiento manguito rotador a realizar es\ndiferente, en funci\u00f3n de si existe solo inflamaci\u00f3n de la zona o rotura. <\/p>\n\n\n\n<p>Cuando la zona est\u00e1 inflamada, es decir se ha\nproducido una tendinitis, el tratamiento es conservador. Se realizan acciones\ncomo: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Intentar corregir la postura. <\/li>\n\n\n\n<li>Fortalecer el hombro con <em>ejercicios\nmanguito rotador<\/em> para que se pueda moverse sin que haya fricci\u00f3n. <\/li>\n\n\n\n<li>Disminuir la actividad f\u00edsica o los\ndeportes que han provocado la inflamaci\u00f3n.<\/li>\n\n\n\n<li>Tomar un tiempo de reposo hasta que\nmejore. <\/li>\n<\/ul>\n\n\n\n<p>Las <strong><a href=\"https:\/\/www.saludonnet.com\/blog\/infiltraciones-para-el-dolor-articular\/\">infiltraciones<\/a><\/strong>,\ngeneralmente de anestesia local y corticoides, tambi\u00e9n pueden ayudar a reducir\nla inflamaci\u00f3n cuando hay mucho dolor y antes de iniciar la rehabilitaci\u00f3n. &nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Cirug\u00eda del manguito rotador<\/strong> <\/h2>\n\n\n\n<p>Cuando la lesi\u00f3n es grave y el paciente no\nresponde al tratamiento conservador se opta por la cirug\u00eda. En pacientes\nmenores de 60 a\u00f1os siempre est\u00e1 indicado el tratamiento quir\u00fargico cuando\nexiste una rotura completa de los tendones. En personas de m\u00e1s edad, si no\nprovoca mucho dolor, a veces no se opera. <\/p>\n\n\n\n<p>El prop\u00f3sito principal de la intervenci\u00f3n es <strong>disminuir\nel roce que provoca el acromion sobre los tendones del manguito de los\nrotadores<\/strong>. En caso de rotura de los tendones se reparan y se colocan en la\nzona de inserci\u00f3n del hueso, mediante unos anclajes. <\/p>\n\n\n\n<p>La intervenci\u00f3n se lleva a cabo con anestesia\ngeneral y el procedimiento se realiza de forma <strong>artrosc\u00f3pica<\/strong>. Tras un periodo\nde reposo el tejido cicatriza sobre el tend\u00f3n. En la mayor\u00eda de los casos, si\nla rotura no es muy grande esta cirug\u00eda resuelve los s\u00edntomas. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Rehabilitaci\u00f3n manguito rotador<\/strong> <\/h2>\n\n\n\n<p>Se trata de una intervenci\u00f3n quir\u00fargica ambulatoria\ncon un postoperatorio de entre 4 y 6 semanas inmovilizado con un cabestrillo y realizando\npeque\u00f1os ejercicios. A partir del tercer mes el paciente puede realizar una\nrecuperaci\u00f3n m\u00e1s intensa, con <strong>ejercicios de fortalecimiento<\/strong>. No\nobstante, es frecuente que hasta pasado un a\u00f1o no se recupere la movilidad que\nse ten\u00eda antes de la lesi\u00f3n. <\/p>\n\n\n\n<p>Si piensas que puedes tener alg\u00fan problema en el\nmanguito rotador te recomendamos que acudas al m\u00e9dico. En <strong><a href=\"https:\/\/www.saludonnet.com\/\">SaludOnNet<\/a><\/strong> contamos con\ntraumat\u00f3logos que pueden ayudarte con esta patolog\u00eda. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor. <\/p>\n","protected":false},"author":20,"featured_media":11303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[261],"class_list":["post-11287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-traumatologia-y-cirugia-ortopedica","tag-3582-consulta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador<\/title>\n<meta name=\"description\" content=\"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador\" \/>\n<meta property=\"og:description\" content=\"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog SaludOnNet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/SaludOnNet\/214957498526536\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-10T15:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T16:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2022\/01\/manguito-rotador.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo M\u00e9dico de SaludOnNet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador\" \/>\n<meta name=\"twitter:description\" content=\"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.\" \/>\n<meta name=\"twitter:creator\" content=\"@saludonnet\" \/>\n<meta name=\"twitter:site\" content=\"@saludonnet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo M\u00e9dico de SaludOnNet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/\"},\"author\":{\"name\":\"Equipo M\u00e9dico de SaludOnNet\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/person\\\/50995e01cc9d6c9f29ae18d979eeff1b\"},\"headline\":\"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador\",\"datePublished\":\"2026-01-10T15:17:00+00:00\",\"dateModified\":\"2026-01-29T16:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/\"},\"wordCount\":838,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/manguito-rotador.jpg\",\"keywords\":[\"Consulta de Traumatolog\u00eda y Cirug\u00eda Ortop\u00e9dica\"],\"articleSection\":[\"Traumatolog\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/\",\"name\":\"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/manguito-rotador.jpg\",\"datePublished\":\"2026-01-10T15:17:00+00:00\",\"dateModified\":\"2026-01-29T16:00:39+00:00\",\"description\":\"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/manguito-rotador.jpg\",\"contentUrl\":\"https:\\\/\\\/soncdn.azureedge.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/manguito-rotador.jpg\",\"width\":800,\"height\":400,\"caption\":\"chico con dolor en el hombro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traumatolog\u00eda\",\"item\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/topic\\\/traumatologia-y-cirugia-ortopedica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/\",\"name\":\"Blog SaludOnNet\",\"description\":\"Un espacio donde encontrar\u00e1s consejos y art\u00edculos para cuidar de tu salud\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#organization\",\"name\":\"SaludOnNet\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Logo-SaludOnNet.png\",\"contentUrl\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Logo-SaludOnNet.png\",\"width\":1140,\"height\":377,\"caption\":\"SaludOnNet\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/SaludOnNet\\\/214957498526536\",\"https:\\\/\\\/x.com\\\/saludonnet\",\"https:\\\/\\\/www.instagram.com\\\/saludonnet\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/saludonnet\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCag68GsnagqzNb6C3G-S9vQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/#\\\/schema\\\/person\\\/50995e01cc9d6c9f29ae18d979eeff1b\",\"name\":\"Equipo M\u00e9dico de SaludOnNet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g\",\"caption\":\"Equipo M\u00e9dico de SaludOnNet\"},\"description\":\"Art\u00edculo elaborado por el equipo m\u00e9dico de SaludOnNet, compuesto por especialistas destacados en su \u00e1rea.\",\"url\":\"https:\\\/\\\/www.saludonnet.com\\\/blog\\\/author\\\/saludonnet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador","description":"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/","og_locale":"es_ES","og_type":"article","og_title":"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador","og_description":"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.","og_url":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/","og_site_name":"Blog SaludOnNet","article_publisher":"https:\/\/www.facebook.com\/pages\/SaludOnNet\/214957498526536","article_published_time":"2026-01-10T15:17:00+00:00","article_modified_time":"2026-01-29T16:00:39+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2022\/01\/manguito-rotador.jpg","type":"image\/jpeg"}],"author":"Equipo M\u00e9dico de SaludOnNet","twitter_card":"summary_large_image","twitter_title":"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador","twitter_description":"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.","twitter_creator":"@saludonnet","twitter_site":"@saludonnet","twitter_misc":{"Escrito por":"Equipo M\u00e9dico de SaludOnNet","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#article","isPartOf":{"@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/"},"author":{"name":"Equipo M\u00e9dico de SaludOnNet","@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/person\/50995e01cc9d6c9f29ae18d979eeff1b"},"headline":"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador","datePublished":"2026-01-10T15:17:00+00:00","dateModified":"2026-01-29T16:00:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/"},"wordCount":838,"commentCount":0,"publisher":{"@id":"https:\/\/www.saludonnet.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#primaryimage"},"thumbnailUrl":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2022\/01\/manguito-rotador.jpg","keywords":["Consulta de Traumatolog\u00eda y Cirug\u00eda Ortop\u00e9dica"],"articleSection":["Traumatolog\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/","url":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/","name":"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador","isPartOf":{"@id":"https:\/\/www.saludonnet.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#primaryimage"},"image":{"@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#primaryimage"},"thumbnailUrl":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2022\/01\/manguito-rotador.jpg","datePublished":"2026-01-10T15:17:00+00:00","dateModified":"2026-01-29T16:00:39+00:00","description":"La lesi\u00f3n del manguito rotador es muy com\u00fan y se produce cuando el hueso acromion del hombro fricciona con los tendones y causa un dolor.","breadcrumb":{"@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#primaryimage","url":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2022\/01\/manguito-rotador.jpg","contentUrl":"https:\/\/soncdn.azureedge.net\/blog\/wp-content\/uploads\/2022\/01\/manguito-rotador.jpg","width":800,"height":400,"caption":"chico con dolor en el hombro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.saludonnet.com\/blog\/dolor-en-el-hombro-al-levantar-el-brazo-lesion-del-manguito-rotador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.saludonnet.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Traumatolog\u00eda","item":"https:\/\/www.saludonnet.com\/blog\/topic\/traumatologia-y-cirugia-ortopedica\/"},{"@type":"ListItem","position":3,"name":"Dolor en el hombro al levantar el brazo: lesi\u00f3n del manguito rotador"}]},{"@type":"WebSite","@id":"https:\/\/www.saludonnet.com\/blog\/#website","url":"https:\/\/www.saludonnet.com\/blog\/","name":"Blog SaludOnNet","description":"Un espacio donde encontrar\u00e1s consejos y art\u00edculos para cuidar de tu salud","publisher":{"@id":"https:\/\/www.saludonnet.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saludonnet.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.saludonnet.com\/blog\/#organization","name":"SaludOnNet","url":"https:\/\/www.saludonnet.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2019\/07\/Logo-SaludOnNet.png","contentUrl":"https:\/\/www.saludonnet.com\/blog\/wp-content\/uploads\/2019\/07\/Logo-SaludOnNet.png","width":1140,"height":377,"caption":"SaludOnNet"},"image":{"@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/SaludOnNet\/214957498526536","https:\/\/x.com\/saludonnet","https:\/\/www.instagram.com\/saludonnet\/","https:\/\/www.linkedin.com\/company\/saludonnet\/","https:\/\/www.youtube.com\/channel\/UCag68GsnagqzNb6C3G-S9vQ"]},{"@type":"Person","@id":"https:\/\/www.saludonnet.com\/blog\/#\/schema\/person\/50995e01cc9d6c9f29ae18d979eeff1b","name":"Equipo M\u00e9dico de SaludOnNet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ac89931d2ef75704f29e63e12335967620a1f7ac37c69f6f97ad72b9ac6496d?s=96&d=mm&r=g","caption":"Equipo M\u00e9dico de SaludOnNet"},"description":"Art\u00edculo elaborado por el equipo m\u00e9dico de SaludOnNet, compuesto por especialistas destacados en su \u00e1rea.","url":"https:\/\/www.saludonnet.com\/blog\/author\/saludonnet\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts\/11287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/comments?post=11287"}],"version-history":[{"count":16,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts\/11287\/revisions"}],"predecessor-version":[{"id":15189,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/posts\/11287\/revisions\/15189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/media\/11303"}],"wp:attachment":[{"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/media?parent=11287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/categories?post=11287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saludonnet.com\/blog\/wp-json\/wp\/v2\/tags?post=11287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}